{"id":1279,"date":"2026-03-19T15:15:17","date_gmt":"2026-03-19T14:15:17","guid":{"rendered":"https:\/\/lamainnoire.preprod.andycamicci.fr\/?post_type=product&#038;p=1279"},"modified":"2026-05-20T16:59:50","modified_gmt":"2026-05-20T14:59:50","slug":"pumpkin-latte-barista-bio","status":"publish","type":"product","link":"https:\/\/lamainnoirecollective.com\/en\/product\/pumpkin-latte-barista-bio\/","title":{"rendered":"Pumpkin Latte Barista Organic 100g"},"content":{"rendered":"<section id=\"ac-block_03a727038e2f8dd7bc26bc46f90ff942\" class=\"block-lmn-product-description-tabs\">\r\n\r\n    <div class=\"container container-small\">\r\n\r\n        <div class=\"tabs-title\">\r\n                                            <div id=\"description\" class=\"tab active\" data-tab=\"description\">\r\n                    <h2 class=\"tab-title\"><button>Description<\/button><\/h2>\r\n                <\/div>\r\n                                            <div id=\"ingredients\" class=\"tab\" data-tab=\"ingredients\">\r\n                    <h2 class=\"tab-title\"><button>Ingredients<\/button><\/h2>\r\n                <\/div>\r\n                                            <div id=\"comment-lutiliser\" class=\"tab\" data-tab=\"comment-lutiliser\">\r\n                    <h2 class=\"tab-title\"><button>How to use it<\/button><\/h2>\r\n                <\/div>\r\n                                            <div id=\"bienfaits\" class=\"tab\" data-tab=\"bienfaits\">\r\n                    <h2 class=\"tab-title\"><button>Benefits<\/button><\/h2>\r\n                <\/div>\r\n                    <\/div>\r\n\r\n        <div class=\"tabs-content\">\r\n                                            <div class=\"tab active\" data-tab=\"description\">\r\n                    \r\n                    <h2 class=\"tab-title\"><button>Description<span>&nbsp;+<\/span><\/button><\/h2>\r\n                    \r\n                    <div class=\"tab-content-container\">\r\n\r\n                                                    <div class=\"image\">\r\n                                <img decoding=\"async\" src=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/pumpkin-ramequin-poudre-1024x1024.png\" alt=\"\" >                            <\/div>\r\n                        \r\n                            \r\n                        <div class=\"content\">\r\n                            <p data-start=\"0\" data-end=\"265\">Pumpkin, the star of autumn, is enhanced here by a blend of warming spices: cinnamon, ginger, and black pepper. This latte is free of artificial flavors, lightly sweetened, and naturally rich in antioxidants and beta-carotene, which gives it its beautiful golden color.<\/p>\n<p data-start=\"267\" data-end=\"399\" data-is-last-node=\"\" data-is-only-node=\"\">The result: a generous and comforting drink, full of character, where the spices accompany the squash without ever dominating it.<\/p>\n<p data-start=\"267\" data-end=\"399\" data-is-last-node=\"\" data-is-only-node=\"\"><span class=\"lmn-mce-label\">100% bio<\/span> <span class=\"lmn-mce-label\">vegan<\/span> <span class=\"lmn-mce-label\">Seasonal latte<\/span><\/p>\n                        <\/div>\r\n                        \r\n                    <\/div>\r\n                    \r\n                <\/div>\r\n                                            <div class=\"tab\" data-tab=\"ingredients\">\r\n                    \r\n                    <h2 class=\"tab-title\"><button>Ingredients<span>&nbsp;+<\/span><\/button><\/h2>\r\n                    \r\n                    <div class=\"tab-content-container\">\r\n\r\n                            \r\n                        <div class=\"content\">\r\n                            <p><span data-sheets-root=\"1\"><strong>Ingredients :<\/strong> Pumpkin flour*, unrefined beet sugar (FR)*, cinnamon*, ginger*, black pepper*.<\/span><\/p>\n<p><span data-sheets-root=\"1\">*Product from organic farming<\/span><\/p>\n<p><strong>Allergens:<\/strong> May contain traces of gluten, nuts, black sesame, mustard, celery and peanuts.<\/p>\n<p>&nbsp;<\/p>\n<h4>Storage advice:<\/h4>\n<p>Minimum durability date: 24 months (guarantee of at least 18 months upon delivery).<\/p>\n<p>Store at room temperature, in a dry place and away from light.<\/p>\n<p>Close tightly after use.<\/p>\n                        <\/div>\r\n                        \r\n                    <\/div>\r\n                    \r\n                <\/div>\r\n                                            <div class=\"tab\" data-tab=\"comment-lutiliser\">\r\n                    \r\n                    <h2 class=\"tab-title\"><button>How to use it<span>&nbsp;+<\/span><\/button><\/h2>\r\n                    \r\n                    <div class=\"tab-content-container\">\r\n\r\n                            \r\n                        <div class=\"content\">\r\n                            <div class=\"lmn-mce-icons-row\"  data-title-style=\"medium\" data-icon-size=\"medium\" data-align=\"left\"><div class=\"lmn-mce-icons-row-title\">Hot<\/div><div class=\"icons\">\n<p><span class=\"lmn-mce-icon\" aria-hidden=\"true\" data-lmn-icon=\"lfal_poudre\"><\/span> 2 cc (10g)<\/p>\n<p><span class=\"lmn-mce-icon\" aria-hidden=\"true\" data-lmn-icon=\"action_lait\"><\/span> 200 ml<\/p>\n<p><span class=\"lmn-mce-icon\" aria-hidden=\"true\" data-lmn-icon=\"action_touiller\"><\/span><\/p>\n<p><span class=\"lmn-mce-icon\" aria-hidden=\"true\" data-lmn-icon=\"action_tasse_chaude\"><\/span><\/p>\n<\/div><\/div>\n<div class=\"lmn-mce-icons-row\"  data-title-style=\"medium\" data-icon-size=\"medium\" data-align=\"left\"><div class=\"lmn-mce-icons-row-title\">Cold<\/div><div class=\"icons\">\n<p><span class=\"lmn-mce-icon\" aria-hidden=\"true\" data-lmn-icon=\"lfal_eau\"><\/span> 40 ml<\/p>\n<p><span class=\"lmn-mce-icon\" aria-hidden=\"true\" data-lmn-icon=\"action_cuillere_full\"><\/span> 2 cc (10g)<\/p>\n<p><span class=\"lmn-mce-icon\" aria-hidden=\"true\" data-lmn-icon=\"action_touiller\"><\/span><\/p>\n<p><span class=\"lmn-mce-icon\" aria-hidden=\"true\" data-lmn-icon=\"matcha_lait\"><\/span> 150 ml<\/p>\n<p><span class=\"lmn-mce-icon\" aria-hidden=\"true\" data-lmn-icon=\"action_ajouter_glacons\"><\/span><\/p>\n<p><span class=\"lmn-mce-icon\" aria-hidden=\"true\" data-lmn-icon=\"lfal_boisson_fraiche\"><\/span><\/p>\n<\/div><\/div>\n                        <\/div>\r\n                        \r\n                    <\/div>\r\n                    \r\n                <\/div>\r\n                                            <div class=\"tab\" data-tab=\"bienfaits\">\r\n                    \r\n                    <h2 class=\"tab-title\"><button>Benefits<span>&nbsp;+<\/span><\/button><\/h2>\r\n                    \r\n                    <div class=\"tab-content-container\">\r\n\r\n                            \r\n                        <div class=\"content\">\r\n                            <div class=\"lmn-mce-icons-row\"  data-icon-size=\"medium\" data-align=\"center\"><div class=\"icons\">\n<p><span class=\"lmn-mce-icon\" aria-hidden=\"true\" data-lmn-icon=\"bienfait_antioxydant\"><\/span> Antioxidant<\/p>\n<p><span class=\"lmn-mce-icon\" aria-hidden=\"true\" data-lmn-icon=\"bienfait_digestion_02\"><\/span> Favorite<br \/>digestion<\/p>\n<p><span class=\"lmn-mce-icon\" aria-hidden=\"true\" data-lmn-icon=\"bienfait_systeme_immunitaire\"><\/span> Strengthens<br \/>immunity<\/p>\n<\/div><\/div>\n                        <\/div>\r\n                        \r\n                    <\/div>\r\n                    \r\n                <\/div>\r\n                    <\/div>\r\n        \r\n    <\/div>\r\n\r\n    \r\n<\/section>\r\n\n\n\r\n<div \r\n    id=\"ac-block_8ae7ddbe791efaf1182e7895e0dd7a0f\" \r\n    class=\"block-lmn-spacing spacing-100\" \r\n    ><\/div>\r\n\n\n\r\n<section id=\"ac-block_766f971c44da96934b52afb977970380\" class=\"block-lmn-product-info-tabs\">\r\n\r\n    <div class=\"columns\">\r\n\r\n        <div class=\"image-column\">\r\n            <div class=\"image\">\r\n                <img decoding=\"async\" src=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/Pumpkin-Latte-butternut-squash-1-683x1024.jpg\" alt=\"\" >            <\/div>\r\n        <\/div>\r\n\r\n        <div class=\"content-column\">\r\n\r\n            <div class=\"content\">\r\n                                    <h2 class=\"title\">We&#039;ll tell you more about the pumpkin<\/h2>\r\n                \r\n                                    <div class=\"description\">\r\n                        Pumpkin is rich in antioxidants, particularly beta-carotene, which supports the immune system and healthy skin and eyes. Sweet and nutritious, it makes for a comforting and balanced drink.                    <\/div>\r\n                \r\n                \r\n                    <div class=\"items\">\r\n\r\n                                            <div class=\"item active\">\r\n                            <h3 class=\"item-title\"><button>Why combine pumpkin and spices?<\/button><\/h3>\r\n                            <div class=\"item-description\"><p>Combining pumpkin and spices enhances the natural sweetness of the squash. The spices add warmth, depth, and a touch of indulgence, resulting in a more balanced and comforting drink.<\/p>\n<\/div>\r\n                        <\/div>\r\n                                            <div class=\"item\">\r\n                            <h3 class=\"item-title\"><button>Where does our pumpkin come from?<\/button><\/h3>\r\n                            <div class=\"item-description\"><p>Our pumpkin flour comes from Italy and is certified organic. It is guaranteed free of colorings and flavor enhancers.<\/p>\n<\/div>\r\n                        <\/div>\r\n                    \r\n                    <\/div>\r\n\r\n                    \r\n                                    \r\n            <\/div>\r\n            \r\n        <\/div>\r\n        \r\n    <\/div>\r\n\r\n    \r\n<\/section>\r\n\n\n\n\n\n\n\n\n\n\n\r\n<div \r\n    id=\"ac-block_8ae7ddbe791efaf1182e7895e0dd7a0f\" \r\n    class=\"block-lmn-spacing spacing-100\" \r\n    ><\/div>\r\n\n\n\r\n<section id=\"reviews\" class=\"block-lmn-product-reviews\" data-id=\"reviews-6a581cf0d5882\">\r\n\r\n    \r\n<div class=\"container-small\">\r\n\r\n    <div class=\"columns\">\r\n\r\n        <div class=\"left-column\">\r\n\r\n                            <h2 class=\"title\">They like <br \/>\r\nour products<\/h2>\r\n            \r\n                            <button class=\"write-review-button\">Write a review<\/button>\r\n            \r\n            <div class=\"slider-container\">\r\n\r\n                <div class=\"splide\">\r\n                    <div class=\"splide__track\">\r\n                        <div class=\"splide__list\">\r\n                                                            <div class=\"splide__slide item\">\r\n\r\n                                                                            <div class=\"image\">\r\n                                            <img decoding=\"async\" src=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/04\/IMG_0049-580x1024.jpg\" alt=\"\" >                                        <\/div>\r\n                                    \r\n                                                                    <\/div>\r\n                                                            <div class=\"splide__slide item\">\r\n\r\n                                                                            <div class=\"video-container\">\r\n\r\n                                            <video class=\"video-js\" data-setup='{}' controls>\r\n                                                <source src=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/07\/0702-2.mp4\" type=\"video\/mp4\">\r\n                                                Your browser does not support the video tag.\r\n                                            <\/video>\r\n                                            \r\n                                        <\/div>\r\n\r\n                                                                    <\/div>\r\n                                                            <div class=\"splide__slide item\">\r\n\r\n                                                                            <div class=\"video-container\">\r\n\r\n                                            <video class=\"video-js\" data-setup='{}' controls>\r\n                                                <source src=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/07\/0702-2-copie.mp4\" type=\"video\/mp4\">\r\n                                                Your browser does not support the video tag.\r\n                                            <\/video>\r\n                                            \r\n                                        <\/div>\r\n\r\n                                                                    <\/div>\r\n                                                            <div class=\"splide__slide item\">\r\n\r\n                                                                            <div class=\"video-container\">\r\n\r\n                                            <video class=\"video-js\" data-setup='{}' controls>\r\n                                                <source src=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/07\/0702-2-copie-2.mp4\" type=\"video\/mp4\">\r\n                                                Your browser does not support the video tag.\r\n                                            <\/video>\r\n                                            \r\n                                        <\/div>\r\n\r\n                                                                    <\/div>\r\n                                                            <div class=\"splide__slide item\">\r\n\r\n                                                                            <div class=\"video-container\">\r\n\r\n                                            <video class=\"video-js\" data-setup='{}' controls>\r\n                                                <source src=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/07\/0702-2-copie-1.mp4\" type=\"video\/mp4\">\r\n                                                Your browser does not support the video tag.\r\n                                            <\/video>\r\n                                            \r\n                                        <\/div>\r\n\r\n                                                                    <\/div>\r\n                                                            <div class=\"splide__slide item\">\r\n\r\n                                                                            <div class=\"image\">\r\n                                            <img decoding=\"async\" src=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/04\/IMG_9925-587x1024.jpg\" alt=\"\" >                                        <\/div>\r\n                                    \r\n                                                                    <\/div>\r\n                                                            <div class=\"splide__slide item\">\r\n\r\n                                                                            <div class=\"image\">\r\n                                            <img decoding=\"async\" src=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/04\/IMG_0053-583x1024.jpg\" alt=\"\" >                                        <\/div>\r\n                                    \r\n                                                                    <\/div>\r\n                                                            <div class=\"splide__slide item\">\r\n\r\n                                                                            <div class=\"image\">\r\n                                            <img decoding=\"async\" src=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/04\/IMG_0051-582x1024.jpg\" alt=\"\" >                                        <\/div>\r\n                                    \r\n                                                                    <\/div>\r\n                                                            <div class=\"splide__slide item\">\r\n\r\n                                                                            <div class=\"image\">\r\n                                            <img decoding=\"async\" src=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/04\/IMG_0050-580x1024.jpg\" alt=\"\" >                                        <\/div>\r\n                                    \r\n                                                                    <\/div>\r\n                                                    <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n\r\n            <\/div>\r\n            \r\n            \r\n            \r\n        <\/div>\r\n\r\n        <div class=\"right-column\">\r\n            <div class=\"reviews\">\r\n\r\n                \r\n                                    \r\n                                            \r\n                        \r\n                        <div class=\"review\" id=\"comment-303\">\r\n                            \r\n                            <div class=\"review-meta\">\r\n                                    \r\n                                                            <\/div>\r\n\r\n                        \r\n                                                        <div class=\"review-description\">\r\n                                Tested and approved. The spices are perfectly balanced and the flavor is truly exceptional. Be careful to follow the measurements indicated on the package, as the natural sugar and spices could be too strong. Perfect for autumn.                            <\/div>\r\n\r\n                            <div class=\"review-rating\">\r\n                                \r\n    <div class=\"rating\">\r\n        <div class=\"stars\" style=\"--rating: 5;\">\r\n            <i class=\"full\"><\/i><i class=\"full\"><\/i><i class=\"full\"><\/i><i class=\"full\"><\/i><i class=\"full\"><\/i>                \r\n                \r\n        <\/div>\r\n        \r\n                \r\n    <\/div>\r\n\r\n                                <\/div>\r\n                            \r\n                           \r\n                                                            \r\n                        <\/div>\r\n                    \r\n                \r\n            <\/div>\r\n\r\n            \r\n        <\/div>\r\n        \r\n    <\/div>\r\n\r\n    \r\n<\/div>\r\n\r\n    <div class=\"lmn-popup review-popup\" data-id=\"reviews-6a581cf0d5882\" data-lenis-prevent>\r\n        <div class=\"popup--inner\">\r\n            <button class=\"popup--close\">\u00d7<\/button>\r\n\r\n            <div class=\"popup--content\">\r\n                <h2 class=\"popup--main-title\">Leave a review<\/h2>\r\n                \r\n                \r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n\r\n    \r\n<\/section>\r\n\n\n\r\n<div \r\n    id=\"ac-block_53bf955d5788baf73c38c0772f7375f3\" \r\n    class=\"block-lmn-spacing spacing-130\" \r\n    ><\/div>\r\n\n\n\n\n\n\n\n\n\n\n\r\n<section id=\"ac-block_2e5402117e6a27ce56ad5283eb9ee3bb\" class=\"block-lmn-slider-products products-display-slider\">\r\n\r\n            \r\n\r\n<div class=\"container container-normal\">\r\n\r\n    \r\n    <div class=\"title-container\">\r\n\r\n        <div class=\"title-component--item layout-simple\">\r\n\r\n            <div class=\"title-column\">\r\n                            \r\n                                    <h2 class=\"title\">Discover our other La Fabrique \u00e0 Latte products<\/h2>                            \r\n                            \r\n                            <\/div>\r\n\r\n            \r\n        <\/div>\r\n\r\n    <\/div>\r\n<\/div>        \r\n    <div class=\"container\">\r\n\r\n                \r\n            <div class=\"slider-container\">\r\n    \r\n                <div class=\"splide\">\r\n                    <div class=\"splide__track\">\r\n                        <div class=\"splide__list\">\r\n                                                            <div class=\"splide__slide item\">\r\n                                    \r\n<article class=\"lmn-stock-status-instock\">\r\n\r\n    <a href=\"https:\/\/lamainnoirecollective.com\/en\/product\/golden-latte-barista-bio\/\">\r\n\r\n        <div class=\"product-image\">\r\n\r\n                        \r\n            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/GLB-retail-Packshot-avec-boisson-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"Golden Latte Barista Bio 100g\" srcset=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/GLB-retail-Packshot-avec-boisson-300x300.jpg 300w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/GLB-retail-Packshot-avec-boisson-1024x1024.jpg 1024w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/GLB-retail-Packshot-avec-boisson-150x150.jpg 150w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/GLB-retail-Packshot-avec-boisson-768x768.jpg 768w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/GLB-retail-Packshot-avec-boisson-1536x1536.jpg 1536w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/GLB-retail-Packshot-avec-boisson-12x12.jpg 12w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/GLB-retail-Packshot-avec-boisson-600x600.jpg 600w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/GLB-retail-Packshot-avec-boisson-100x100.jpg 100w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/GLB-retail-Packshot-avec-boisson.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>        <\/div>\r\n\r\n    <\/a>\r\n\r\n            <div class=\"product-tags\">\r\n                                            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product-tag\/anti-inflammatoire\/\" rel=\"tag\">anti-inflammatory<\/a>\r\n                                            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product-tag\/epice\/\" rel=\"tag\">spicy<\/a>\r\n                                            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product-tag\/vegan\/\" rel=\"tag\">vegan<\/a>\r\n                    <\/div>\r\n    \r\n            \r\n    <div class=\"rating\">\r\n        <div class=\"stars\" style=\"--rating: 5.00;\">\r\n            <i class=\"full\"><\/i><i class=\"full\"><\/i><i class=\"full\"><\/i><i class=\"full\"><\/i><i class=\"full\"><\/i>                \r\n                \r\n        <\/div>\r\n        \r\n                <p class=\"reviews\">\r\n                        (2 Avis)                    <\/p>\r\n                \r\n    <\/div>\r\n\r\n        \r\n    <div class=\"title-container\">\r\n        <h3 class=\"product-title\">\r\n            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product\/golden-latte-barista-bio\/\">\r\n                Organic Golden Latte Barista 100g            <\/a>\r\n        <\/h3>\r\n\r\n        <span class=\"price\"><span class=\"woocommerce-Price-amount amount\">10,90&nbsp;<span class=\"woocommerce-Price-currencySymbol\">\u20ac<\/span><\/span><\/span>\r\n    <\/div>\r\n\r\n    <div class=\"add-to-cart-container\">\r\n        <a href=\"\/en\/wp-json\/wp\/v2\/product\/1279?add-to-cart=1251\" \r\n            class=\"button add_to_cart_button\" \r\n            aria-label=\"Add &quot;Golden Latte Barista Organic 100g&quot; to your cart\" \r\n            rel=\"nofollow\">\r\n            Add to basket        <\/a>\r\n    <\/div>\r\n\r\n\r\n<\/article>                                <\/div>\r\n                                                            <div class=\"splide__slide item\">\r\n                                    \r\n<article class=\"lmn-stock-status-instock\">\r\n\r\n    <a href=\"https:\/\/lamainnoirecollective.com\/en\/product\/purple-latte-barista\/\">\r\n\r\n        <div class=\"product-image\">\r\n\r\n                        \r\n            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PurpLB-retail-Packshot-avec-boisson-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"Purple Latte Barista 100g\" srcset=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PurpLB-retail-Packshot-avec-boisson-300x300.jpg 300w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PurpLB-retail-Packshot-avec-boisson-1024x1024.jpg 1024w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PurpLB-retail-Packshot-avec-boisson-150x150.jpg 150w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PurpLB-retail-Packshot-avec-boisson-768x768.jpg 768w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PurpLB-retail-Packshot-avec-boisson-1536x1536.jpg 1536w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PurpLB-retail-Packshot-avec-boisson-12x12.jpg 12w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PurpLB-retail-Packshot-avec-boisson-600x600.jpg 600w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PurpLB-retail-Packshot-avec-boisson-100x100.jpg 100w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PurpLB-retail-Packshot-avec-boisson.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>        <\/div>\r\n\r\n    <\/a>\r\n\r\n            <div class=\"product-tags\">\r\n                                            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product-tag\/antioxydant\/\" rel=\"tag\">antioxidant<\/a>\r\n                                            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product-tag\/energisant\/\" rel=\"tag\">energizer<\/a>\r\n                                            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product-tag\/gourmand\/\" rel=\"tag\">gourmand<\/a>\r\n                    <\/div>\r\n    \r\n            \r\n    <div class=\"rating\">\r\n        <div class=\"stars\" style=\"--rating: 4.80;\">\r\n            <i class=\"full\"><\/i><i class=\"full\"><\/i><i class=\"full\"><\/i><i class=\"full\"><\/i><i class=\"half\"><\/i>                \r\n                \r\n        <\/div>\r\n        \r\n                <p class=\"reviews\">\r\n                        (15 Avis)                    <\/p>\r\n                \r\n    <\/div>\r\n\r\n        \r\n    <div class=\"title-container\">\r\n        <h3 class=\"product-title\">\r\n            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product\/purple-latte-barista\/\">\r\n                Purple Latte Barista 100g            <\/a>\r\n        <\/h3>\r\n\r\n        <span class=\"price\"><span class=\"woocommerce-Price-amount amount\">14,90&nbsp;<span class=\"woocommerce-Price-currencySymbol\">\u20ac<\/span><\/span><\/span>\r\n    <\/div>\r\n\r\n    <div class=\"add-to-cart-container\">\r\n        <a href=\"\/en\/wp-json\/wp\/v2\/product\/1279?add-to-cart=1334\" \r\n            class=\"button add_to_cart_button\" \r\n            aria-label=\"Add &quot;Purple Latte Barista 100g&quot; to your cart\" \r\n            rel=\"nofollow\">\r\n            Add to basket        <\/a>\r\n    <\/div>\r\n\r\n\r\n<\/article>                                <\/div>\r\n                                                            <div class=\"splide__slide item\">\r\n                                    \r\n<article class=\"lmn-stock-status-instock\">\r\n\r\n    <a href=\"https:\/\/lamainnoirecollective.com\/en\/product\/black-sesame-latte-barista\/\">\r\n\r\n        <div class=\"product-image\">\r\n\r\n                        \r\n            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/A7408770--300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"Black Sesame Latte Barista 100g\" srcset=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/A7408770--300x300.jpg 300w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/A7408770--1024x1024.jpg 1024w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/A7408770--150x150.jpg 150w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/A7408770--768x768.jpg 768w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/A7408770--1536x1536.jpg 1536w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/A7408770--12x12.jpg 12w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/A7408770--600x600.jpg 600w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/A7408770--100x100.jpg 100w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/A7408770-.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>        <\/div>\r\n\r\n    <\/a>\r\n\r\n            <div class=\"product-tags\">\r\n                                            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product-tag\/gourmand\/\" rel=\"tag\">gourmand<\/a>\r\n                                            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product-tag\/purifiant\/\" rel=\"tag\">purifying<\/a>\r\n                                            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product-tag\/reconfortant\/\" rel=\"tag\">comforting<\/a>\r\n                    <\/div>\r\n    \r\n    \r\n    <div class=\"title-container\">\r\n        <h3 class=\"product-title\">\r\n            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product\/black-sesame-latte-barista\/\">\r\n                Black Sesame Latte Barista 100g            <\/a>\r\n        <\/h3>\r\n\r\n        <span class=\"price\"><span class=\"woocommerce-Price-amount amount\">12,90&nbsp;<span class=\"woocommerce-Price-currencySymbol\">\u20ac<\/span><\/span><\/span>\r\n    <\/div>\r\n\r\n    <div class=\"add-to-cart-container\">\r\n        <a href=\"\/en\/wp-json\/wp\/v2\/product\/1279?add-to-cart=1198\" \r\n            class=\"button add_to_cart_button\" \r\n            aria-label=\"Add &quot;Black Sesame Latte Barista 100g&quot; to your cart\" \r\n            rel=\"nofollow\">\r\n            Add to basket        <\/a>\r\n    <\/div>\r\n\r\n\r\n<\/article>                                <\/div>\r\n                                                            <div class=\"splide__slide item\">\r\n                                    \r\n<article class=\"lmn-stock-status-instock\">\r\n\r\n    <a href=\"https:\/\/lamainnoirecollective.com\/en\/product\/pumpkin-latte-barista-bio\/\">\r\n\r\n        <div class=\"product-image\">\r\n\r\n                        \r\n            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PumpLB-retail-Packshot-avec-boisson-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"Pumpkin Latte Barista Bio 100g\" srcset=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PumpLB-retail-Packshot-avec-boisson-300x300.jpg 300w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PumpLB-retail-Packshot-avec-boisson-1024x1024.jpg 1024w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PumpLB-retail-Packshot-avec-boisson-150x150.jpg 150w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PumpLB-retail-Packshot-avec-boisson-768x768.jpg 768w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PumpLB-retail-Packshot-avec-boisson-1536x1536.jpg 1536w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PumpLB-retail-Packshot-avec-boisson-12x12.jpg 12w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PumpLB-retail-Packshot-avec-boisson-600x600.jpg 600w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PumpLB-retail-Packshot-avec-boisson-100x100.jpg 100w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PumpLB-retail-Packshot-avec-boisson.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>        <\/div>\r\n\r\n    <\/a>\r\n\r\n            <div class=\"product-tags\">\r\n                                            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product-tag\/antioxydant\/\" rel=\"tag\">antioxidant<\/a>\r\n                                            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product-tag\/chaleureux\/\" rel=\"tag\">warm<\/a>\r\n                                            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product-tag\/epice\/\" rel=\"tag\">spicy<\/a>\r\n                    <\/div>\r\n    \r\n            \r\n    <div class=\"rating\">\r\n        <div class=\"stars\" style=\"--rating: 5.00;\">\r\n            <i class=\"full\"><\/i><i class=\"full\"><\/i><i class=\"full\"><\/i><i class=\"full\"><\/i><i class=\"full\"><\/i>                \r\n                \r\n        <\/div>\r\n        \r\n                <p class=\"reviews\">\r\n                        (1 Avis)                    <\/p>\r\n                \r\n    <\/div>\r\n\r\n        \r\n    <div class=\"title-container\">\r\n        <h3 class=\"product-title\">\r\n            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product\/pumpkin-latte-barista-bio\/\">\r\n                Pumpkin Latte Barista Organic 100g            <\/a>\r\n        <\/h3>\r\n\r\n        <span class=\"price\"><span class=\"woocommerce-Price-amount amount\">13,90&nbsp;<span class=\"woocommerce-Price-currencySymbol\">\u20ac<\/span><\/span><\/span>\r\n    <\/div>\r\n\r\n    <div class=\"add-to-cart-container\">\r\n        <a href=\"\/en\/wp-json\/wp\/v2\/product\/1279?add-to-cart=1279\" \r\n            class=\"button add_to_cart_button\" \r\n            aria-label=\"Add &quot;Pumpkin Latte Barista Organic 100g&quot; to your cart\" \r\n            rel=\"nofollow\">\r\n            Add to basket        <\/a>\r\n    <\/div>\r\n\r\n\r\n<\/article>                                <\/div>\r\n                                                            <div class=\"splide__slide item\">\r\n                                    \r\n<article class=\"lmn-stock-status-instock\">\r\n\r\n    <a href=\"https:\/\/lamainnoirecollective.com\/en\/product\/green-latte-barista-bio\/\">\r\n\r\n        <div class=\"product-image\">\r\n\r\n                        \r\n            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/GrLB-retail-Packshot-avec-boisson-1-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"Green Latte Barista Bio 100g\" srcset=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/GrLB-retail-Packshot-avec-boisson-1-300x300.jpg 300w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/GrLB-retail-Packshot-avec-boisson-1-1024x1024.jpg 1024w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/GrLB-retail-Packshot-avec-boisson-1-150x150.jpg 150w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/GrLB-retail-Packshot-avec-boisson-1-768x768.jpg 768w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/GrLB-retail-Packshot-avec-boisson-1-1536x1536.jpg 1536w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/GrLB-retail-Packshot-avec-boisson-1-12x12.jpg 12w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/GrLB-retail-Packshot-avec-boisson-1-600x600.jpg 600w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/GrLB-retail-Packshot-avec-boisson-1-100x100.jpg 100w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/GrLB-retail-Packshot-avec-boisson-1.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>        <\/div>\r\n\r\n    <\/a>\r\n\r\n            <div class=\"product-tags\">\r\n                                            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product-tag\/antioxydant\/\" rel=\"tag\">antioxidant<\/a>\r\n                                            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product-tag\/herbace\/\" rel=\"tag\">Herbaceous<\/a>\r\n                                            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product-tag\/vegetal\/\" rel=\"tag\">Vegetal<\/a>\r\n                    <\/div>\r\n    \r\n    \r\n    <div class=\"title-container\">\r\n        <h3 class=\"product-title\">\r\n            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product\/green-latte-barista-bio\/\">\r\n                Organic Green Latte Barista 100g            <\/a>\r\n        <\/h3>\r\n\r\n        <span class=\"price\"><span class=\"woocommerce-Price-amount amount\">17,90&nbsp;<span class=\"woocommerce-Price-currencySymbol\">\u20ac<\/span><\/span><\/span>\r\n    <\/div>\r\n\r\n    <div class=\"add-to-cart-container\">\r\n        <a href=\"\/en\/wp-json\/wp\/v2\/product\/1279?add-to-cart=1316\" \r\n            class=\"button add_to_cart_button\" \r\n            aria-label=\"Add &quot;Green Latte Barista Organic 100g&quot; to your cart\" \r\n            rel=\"nofollow\">\r\n            Add to basket        <\/a>\r\n    <\/div>\r\n\r\n\r\n<\/article>                                <\/div>\r\n                                                            <div class=\"splide__slide item\">\r\n                                    \r\n<article class=\"lmn-stock-status-instock\">\r\n\r\n    <a href=\"https:\/\/lamainnoirecollective.com\/en\/product\/raw-cacao-latte-barista-bio\/\">\r\n\r\n        <div class=\"product-image\">\r\n\r\n                        \r\n            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/RCLB-retail-Packshot-avec-boisson-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"Raw Cacao Latte Barista Bio 100g\" srcset=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/RCLB-retail-Packshot-avec-boisson-300x300.jpg 300w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/RCLB-retail-Packshot-avec-boisson-1024x1024.jpg 1024w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/RCLB-retail-Packshot-avec-boisson-150x150.jpg 150w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/RCLB-retail-Packshot-avec-boisson-768x768.jpg 768w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/RCLB-retail-Packshot-avec-boisson-1536x1536.jpg 1536w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/RCLB-retail-Packshot-avec-boisson-12x12.jpg 12w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/RCLB-retail-Packshot-avec-boisson-600x600.jpg 600w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/RCLB-retail-Packshot-avec-boisson-100x100.jpg 100w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/RCLB-retail-Packshot-avec-boisson.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>        <\/div>\r\n\r\n    <\/a>\r\n\r\n            <div class=\"product-tags\">\r\n                                            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product-tag\/floral\/\" rel=\"tag\">floral<\/a>\r\n                                            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product-tag\/gourmand\/\" rel=\"tag\">gourmand<\/a>\r\n                                            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product-tag\/reconfortant\/\" rel=\"tag\">comforting<\/a>\r\n                    <\/div>\r\n    \r\n    \r\n    <div class=\"title-container\">\r\n        <h3 class=\"product-title\">\r\n            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product\/raw-cacao-latte-barista-bio\/\">\r\n                Raw Cocoa Latte Barista Organic 100g            <\/a>\r\n        <\/h3>\r\n\r\n        <span class=\"price\"><span class=\"woocommerce-Price-amount amount\">11,90&nbsp;<span class=\"woocommerce-Price-currencySymbol\">\u20ac<\/span><\/span><\/span>\r\n    <\/div>\r\n\r\n    <div class=\"add-to-cart-container\">\r\n        <a href=\"\/en\/wp-json\/wp\/v2\/product\/1279?add-to-cart=1270\" \r\n            class=\"button add_to_cart_button\" \r\n            aria-label=\"Add &quot;Raw Cacao Latte Barista Organic 100g&quot; to your cart\" \r\n            rel=\"nofollow\">\r\n            Add to basket        <\/a>\r\n    <\/div>\r\n\r\n\r\n<\/article>                                <\/div>\r\n                                                            <div class=\"splide__slide item\">\r\n                                    \r\n<article class=\"lmn-stock-status-instock\">\r\n\r\n    <a href=\"https:\/\/lamainnoirecollective.com\/en\/product\/chai-latte-barista-bio\/\">\r\n\r\n        <div class=\"product-image\">\r\n\r\n                        \r\n            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/CLB-retail-Packshot-avec-boisson-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"Chai Latte Barista Bio 100g\" srcset=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/CLB-retail-Packshot-avec-boisson-300x300.jpg 300w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/CLB-retail-Packshot-avec-boisson-1024x1024.jpg 1024w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/CLB-retail-Packshot-avec-boisson-150x150.jpg 150w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/CLB-retail-Packshot-avec-boisson-768x768.jpg 768w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/CLB-retail-Packshot-avec-boisson-1536x1536.jpg 1536w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/CLB-retail-Packshot-avec-boisson-12x12.jpg 12w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/CLB-retail-Packshot-avec-boisson-600x600.jpg 600w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/CLB-retail-Packshot-avec-boisson-100x100.jpg 100w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/CLB-retail-Packshot-avec-boisson.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>        <\/div>\r\n\r\n    <\/a>\r\n\r\n            <div class=\"product-tags\">\r\n                                            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product-tag\/antioxydant\/\" rel=\"tag\">antioxidant<\/a>\r\n                                            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product-tag\/epice\/\" rel=\"tag\">spicy<\/a>\r\n                                            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product-tag\/favorise-la-digestion\/\" rel=\"tag\">promotes digestion<\/a>\r\n                    <\/div>\r\n    \r\n            \r\n    <div class=\"rating\">\r\n        <div class=\"stars\" style=\"--rating: 5.00;\">\r\n            <i class=\"full\"><\/i><i class=\"full\"><\/i><i class=\"full\"><\/i><i class=\"full\"><\/i><i class=\"full\"><\/i>                \r\n                \r\n        <\/div>\r\n        \r\n                <p class=\"reviews\">\r\n                        (3 Avis)                    <\/p>\r\n                \r\n    <\/div>\r\n\r\n        \r\n    <div class=\"title-container\">\r\n        <h3 class=\"product-title\">\r\n            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product\/chai-latte-barista-bio\/\">\r\n                Organic Barista Chai Latte 100g            <\/a>\r\n        <\/h3>\r\n\r\n        <span class=\"price\"><span class=\"woocommerce-Price-amount amount\">10,90&nbsp;<span class=\"woocommerce-Price-currencySymbol\">\u20ac<\/span><\/span><\/span>\r\n    <\/div>\r\n\r\n    <div class=\"add-to-cart-container\">\r\n        <a href=\"\/en\/wp-json\/wp\/v2\/product\/1279?add-to-cart=1324\" \r\n            class=\"button add_to_cart_button\" \r\n            aria-label=\"Add &quot;Chai Latte Barista Organic 100g&quot; to your cart\" \r\n            rel=\"nofollow\">\r\n            Add to basket        <\/a>\r\n    <\/div>\r\n\r\n\r\n<\/article>                                <\/div>\r\n                                                            <div class=\"splide__slide item\">\r\n                                    \r\n<article class=\"lmn-stock-status-instock\">\r\n\r\n    <a href=\"https:\/\/lamainnoirecollective.com\/en\/product\/pink-latte-barista-bio\/\">\r\n\r\n        <div class=\"product-image\">\r\n\r\n                        \r\n            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PLB-retail-Packshot-avec-boisson-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"Pink Latte Barista Bio 100g\" srcset=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PLB-retail-Packshot-avec-boisson-300x300.jpg 300w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PLB-retail-Packshot-avec-boisson-1024x1024.jpg 1024w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PLB-retail-Packshot-avec-boisson-150x150.jpg 150w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PLB-retail-Packshot-avec-boisson-768x768.jpg 768w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PLB-retail-Packshot-avec-boisson-1536x1536.jpg 1536w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PLB-retail-Packshot-avec-boisson-12x12.jpg 12w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PLB-retail-Packshot-avec-boisson-600x600.jpg 600w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PLB-retail-Packshot-avec-boisson-100x100.jpg 100w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PLB-retail-Packshot-avec-boisson.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>        <\/div>\r\n\r\n    <\/a>\r\n\r\n            <div class=\"product-tags\">\r\n                                            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product-tag\/antioxydant\/\" rel=\"tag\">antioxidant<\/a>\r\n                                            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product-tag\/gourmand\/\" rel=\"tag\">gourmand<\/a>\r\n                                            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product-tag\/sans-colorant\/\" rel=\"tag\">no colorants<\/a>\r\n                    <\/div>\r\n    \r\n            \r\n    <div class=\"rating\">\r\n        <div class=\"stars\" style=\"--rating: 0;\">\r\n            <i class=\"empty\"><\/i><i class=\"empty\"><\/i><i class=\"empty\"><\/i><i class=\"empty\"><\/i><i class=\"empty\"><\/i>                \r\n                \r\n        <\/div>\r\n        \r\n                <p class=\"reviews\">\r\n                        (1 Avis)                    <\/p>\r\n                \r\n    <\/div>\r\n\r\n        \r\n    <div class=\"title-container\">\r\n        <h3 class=\"product-title\">\r\n            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product\/pink-latte-barista-bio\/\">\r\n                Organic Pink Latte Barista 100g            <\/a>\r\n        <\/h3>\r\n\r\n        <span class=\"price\"><span class=\"woocommerce-Price-amount amount\">11,90&nbsp;<span class=\"woocommerce-Price-currencySymbol\">\u20ac<\/span><\/span><\/span>\r\n    <\/div>\r\n\r\n    <div class=\"add-to-cart-container\">\r\n        <a href=\"\/en\/wp-json\/wp\/v2\/product\/1279?add-to-cart=1307\" \r\n            class=\"button add_to_cart_button\" \r\n            aria-label=\"Add &quot;Pink Latte Barista Organic 100g&quot; to your cart\" \r\n            rel=\"nofollow\">\r\n            Add to basket        <\/a>\r\n    <\/div>\r\n\r\n\r\n<\/article>                                <\/div>\r\n                                                            <div class=\"splide__slide item\">\r\n                                    \r\n<article class=\"lmn-stock-status-instock\">\r\n\r\n    <a href=\"https:\/\/lamainnoirecollective.com\/en\/product\/spiced-raw-cacao-latte-barista\/\">\r\n\r\n        <div class=\"product-image\">\r\n\r\n                        \r\n            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/A7405697-Antoine-Jaussaud-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"Spiced Raw Cacao Latte Barista Bio 100g\" srcset=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/A7405697-Antoine-Jaussaud-300x300.jpg 300w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/A7405697-Antoine-Jaussaud-1024x1024.jpg 1024w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/A7405697-Antoine-Jaussaud-150x150.jpg 150w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/A7405697-Antoine-Jaussaud-768x768.jpg 768w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/A7405697-Antoine-Jaussaud-1536x1536.jpg 1536w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/A7405697-Antoine-Jaussaud-12x12.jpg 12w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/A7405697-Antoine-Jaussaud-600x600.jpg 600w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/A7405697-Antoine-Jaussaud-100x100.jpg 100w, https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/A7405697-Antoine-Jaussaud.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>        <\/div>\r\n\r\n    <\/a>\r\n\r\n            <div class=\"product-tags\">\r\n                                            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product-tag\/epice\/\" rel=\"tag\">spicy<\/a>\r\n                                            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product-tag\/equilibre\/\" rel=\"tag\">balance<\/a>\r\n                                            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product-tag\/reconfortant\/\" rel=\"tag\">comforting<\/a>\r\n                    <\/div>\r\n    \r\n    \r\n    <div class=\"title-container\">\r\n        <h3 class=\"product-title\">\r\n            <a href=\"https:\/\/lamainnoirecollective.com\/en\/product\/spiced-raw-cacao-latte-barista\/\">\r\n                Spiced Raw Cocoa Latte Barista Organic 100g            <\/a>\r\n        <\/h3>\r\n\r\n        <span class=\"price\"><span class=\"woocommerce-Price-amount amount\">11,90&nbsp;<span class=\"woocommerce-Price-currencySymbol\">\u20ac<\/span><\/span><\/span>\r\n    <\/div>\r\n\r\n    <div class=\"add-to-cart-container\">\r\n        <a href=\"\/en\/wp-json\/wp\/v2\/product\/1279?add-to-cart=1242\" \r\n            class=\"button add_to_cart_button\" \r\n            aria-label=\"Add &quot;Spiced Raw Cacao Latte Barista Organic 100g&quot; to your cart\" \r\n            rel=\"nofollow\">\r\n            Add to basket        <\/a>\r\n    <\/div>\r\n\r\n\r\n<\/article>                                <\/div>\r\n                                                    <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n    \r\n            <\/div>\r\n            \r\n        \r\n\r\n\r\n    <\/div>\r\n\r\n        \r\n<\/section>\r\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>This is a true Spiced Pumpkin Latte. Not just a blend of &quot;Pumpkin Spice,&quot; but a real butternut squash base, combined with a precise balance of spices for a result that is both indulgent and perfectly balanced. A comforting, lightly sweetened drink where the natural sweetness of the squash shines through.<\/p>\n<p>The sachet contains 10 drinks. <\/p>","protected":false},"featured_media":1282,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":true},"product_sale_tag":[],"product_brand":[],"product_cat":[54],"product_tag":[75,87,65],"class_list":["post-1279","product","type-product","status-publish","has-post-thumbnail","product_cat-la-fabrique-a-latte","product_tag-antioxydant","product_tag-chaleureux","product_tag-epice","product_shipping_class-enveloppe","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"exclude_global_add_ons":[],"addons":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pumpkin Latte Barista Bio 100g - La Main Noire<\/title>\n<meta name=\"description\" content=\"Un Pumpkin Latte gourmand et \u00e9quilibr\u00e9, aux \u00e9pices chaleureuses. Une boisson r\u00e9confortante, peu sucr\u00e9e, o\u00f9 la douceur de la courge s\u2019exprime pleinement.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lamainnoirecollective.com\/en\/product\/pumpkin-latte-barista-bio\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pumpkin Latte Barista Bio 100g - La Main Noire\" \/>\n<meta property=\"og:description\" content=\"Un Pumpkin Latte gourmand et \u00e9quilibr\u00e9, aux \u00e9pices chaleureuses. Une boisson r\u00e9confortante, peu sucr\u00e9e, o\u00f9 la douceur de la courge s\u2019exprime pleinement.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lamainnoirecollective.com\/en\/product\/pumpkin-latte-barista-bio\/\" \/>\n<meta property=\"og:site_name\" content=\"La Main Noire\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-20T14:59:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PumpLB-retail-Packshot-avec-boisson.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lamainnoirecollective.com\\\/produit\\\/pumpkin-latte-barista-bio\\\/\",\"url\":\"https:\\\/\\\/lamainnoirecollective.com\\\/produit\\\/pumpkin-latte-barista-bio\\\/\",\"name\":\"Pumpkin Latte Barista Bio 100g - La Main Noire\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lamainnoirecollective.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lamainnoirecollective.com\\\/produit\\\/pumpkin-latte-barista-bio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lamainnoirecollective.com\\\/produit\\\/pumpkin-latte-barista-bio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lamainnoirecollective.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/PumpLB-retail-Packshot-avec-boisson.jpg\",\"datePublished\":\"2026-03-19T14:15:17+00:00\",\"dateModified\":\"2026-05-20T14:59:50+00:00\",\"description\":\"Un Pumpkin Latte gourmand et \u00e9quilibr\u00e9, aux \u00e9pices chaleureuses. Une boisson r\u00e9confortante, peu sucr\u00e9e, o\u00f9 la douceur de la courge s\u2019exprime pleinement.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lamainnoirecollective.com\\\/produit\\\/pumpkin-latte-barista-bio\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lamainnoirecollective.com\\\/produit\\\/pumpkin-latte-barista-bio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/lamainnoirecollective.com\\\/produit\\\/pumpkin-latte-barista-bio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lamainnoirecollective.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/PumpLB-retail-Packshot-avec-boisson.jpg\",\"contentUrl\":\"https:\\\/\\\/lamainnoirecollective.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/PumpLB-retail-Packshot-avec-boisson.jpg\",\"width\":2048,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lamainnoirecollective.com\\\/produit\\\/pumpkin-latte-barista-bio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lamainnoirecollective.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/lamainnoirecollective.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pumpkin Latte Barista Bio 100g\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lamainnoirecollective.com\\\/#website\",\"url\":\"https:\\\/\\\/lamainnoirecollective.com\\\/\",\"name\":\"La Main Noire\",\"description\":\"Innovative products for inspired people\",\"publisher\":{\"@id\":\"https:\\\/\\\/lamainnoirecollective.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lamainnoirecollective.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lamainnoirecollective.com\\\/#organization\",\"name\":\"La Main Noire\",\"url\":\"https:\\\/\\\/lamainnoirecollective.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/lamainnoirecollective.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lamainnoirecollective.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/logo-la-main-noire.png\",\"contentUrl\":\"https:\\\/\\\/lamainnoirecollective.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/logo-la-main-noire.png\",\"width\":92,\"height\":124,\"caption\":\"La Main Noire\"},\"image\":{\"@id\":\"https:\\\/\\\/lamainnoirecollective.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pumpkin Latte Barista Bio 100g - La Main Noire","description":"Un Pumpkin Latte gourmand et \u00e9quilibr\u00e9, aux \u00e9pices chaleureuses. Une boisson r\u00e9confortante, peu sucr\u00e9e, o\u00f9 la douceur de la courge s\u2019exprime pleinement.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lamainnoirecollective.com\/en\/product\/pumpkin-latte-barista-bio\/","og_locale":"en_GB","og_type":"article","og_title":"Pumpkin Latte Barista Bio 100g - La Main Noire","og_description":"Un Pumpkin Latte gourmand et \u00e9quilibr\u00e9, aux \u00e9pices chaleureuses. Une boisson r\u00e9confortante, peu sucr\u00e9e, o\u00f9 la douceur de la courge s\u2019exprime pleinement.","og_url":"https:\/\/lamainnoirecollective.com\/en\/product\/pumpkin-latte-barista-bio\/","og_site_name":"La Main Noire","article_modified_time":"2026-05-20T14:59:50+00:00","og_image":[{"width":2048,"height":2048,"url":"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PumpLB-retail-Packshot-avec-boisson.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lamainnoirecollective.com\/produit\/pumpkin-latte-barista-bio\/","url":"https:\/\/lamainnoirecollective.com\/produit\/pumpkin-latte-barista-bio\/","name":"Pumpkin Latte Barista Bio 100g - La Main Noire","isPartOf":{"@id":"https:\/\/lamainnoirecollective.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lamainnoirecollective.com\/produit\/pumpkin-latte-barista-bio\/#primaryimage"},"image":{"@id":"https:\/\/lamainnoirecollective.com\/produit\/pumpkin-latte-barista-bio\/#primaryimage"},"thumbnailUrl":"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PumpLB-retail-Packshot-avec-boisson.jpg","datePublished":"2026-03-19T14:15:17+00:00","dateModified":"2026-05-20T14:59:50+00:00","description":"Un Pumpkin Latte gourmand et \u00e9quilibr\u00e9, aux \u00e9pices chaleureuses. Une boisson r\u00e9confortante, peu sucr\u00e9e, o\u00f9 la douceur de la courge s\u2019exprime pleinement.","breadcrumb":{"@id":"https:\/\/lamainnoirecollective.com\/produit\/pumpkin-latte-barista-bio\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lamainnoirecollective.com\/produit\/pumpkin-latte-barista-bio\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/lamainnoirecollective.com\/produit\/pumpkin-latte-barista-bio\/#primaryimage","url":"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PumpLB-retail-Packshot-avec-boisson.jpg","contentUrl":"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2026\/03\/PumpLB-retail-Packshot-avec-boisson.jpg","width":2048,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/lamainnoirecollective.com\/produit\/pumpkin-latte-barista-bio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lamainnoirecollective.com\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/lamainnoirecollective.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Pumpkin Latte Barista Bio 100g"}]},{"@type":"WebSite","@id":"https:\/\/lamainnoirecollective.com\/#website","url":"https:\/\/lamainnoirecollective.com\/","name":"La Main Noire","description":"Innovative products for inspired people","publisher":{"@id":"https:\/\/lamainnoirecollective.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lamainnoirecollective.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/lamainnoirecollective.com\/#organization","name":"La Main Noire","url":"https:\/\/lamainnoirecollective.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/lamainnoirecollective.com\/#\/schema\/logo\/image\/","url":"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2025\/12\/logo-la-main-noire.png","contentUrl":"https:\/\/lamainnoirecollective.com\/wp-content\/uploads\/2025\/12\/logo-la-main-noire.png","width":92,"height":124,"caption":"La Main Noire"},"image":{"@id":"https:\/\/lamainnoirecollective.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lamainnoirecollective.com\/en\/wp-json\/wp\/v2\/product\/1279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lamainnoirecollective.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lamainnoirecollective.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lamainnoirecollective.com\/en\/wp-json\/wp\/v2\/comments?post=1279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lamainnoirecollective.com\/en\/wp-json\/wp\/v2\/media\/1282"}],"wp:attachment":[{"href":"https:\/\/lamainnoirecollective.com\/en\/wp-json\/wp\/v2\/media?parent=1279"}],"wp:term":[{"taxonomy":"product_sale_tag","embeddable":true,"href":"https:\/\/lamainnoirecollective.com\/en\/wp-json\/wp\/v2\/product_sale_tag?post=1279"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lamainnoirecollective.com\/en\/wp-json\/wp\/v2\/product_brand?post=1279"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lamainnoirecollective.com\/en\/wp-json\/wp\/v2\/product_cat?post=1279"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lamainnoirecollective.com\/en\/wp-json\/wp\/v2\/product_tag?post=1279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}